{"id":96565,"date":"2021-03-30T14:20:14","date_gmt":"2021-03-30T17:20:14","guid":{"rendered":"http:\/\/127.0.0.1\/acs\/economia-programa-de-protecao-ao-emprego-deve-manter-regras-de-2020-e-beneficiar-4-milhoes-diz-governo\/"},"modified":"2021-03-30T14:20:14","modified_gmt":"2021-03-30T17:20:14","slug":"economia-programa-de-protecao-ao-emprego-deve-manter-regras-de-2020-e-beneficiar-4-milhoes-diz-governo","status":"publish","type":"post","link":"https:\/\/acs.org.br\/academy\/economia-programa-de-protecao-ao-emprego-deve-manter-regras-de-2020-e-beneficiar-4-milhoes-diz-governo\/","title":{"rendered":"ECONOMIA: Programa de prote\u00e7\u00e3o ao emprego deve manter regras de 2020 e beneficiar 4 milh\u00f5es, diz governo"},"content":{"rendered":"<p>Fonte: G1&nbsp;&nbsp;<\/p>\n<p>O programa de prote\u00e7\u00e3o ao emprego ser\u00e1 renovado neste ano com o mesmo modelo adotado em 2020, e custar\u00e1 cerca de R$ 10 bilh\u00f5es, informou nesta ter\u00e7a-feira (30) o secret\u00e1rio especial de Previd\u00eancia e Trabalho do Minist\u00e9rio da Economia, Bruno Bianco.&nbsp;<\/p>\n<p><a href=\"https:\/\/g1.globo.com\/economia\/noticia\/2021\/03\/30\/programa-de-protecao-ao-emprego-deve-manter-regras-de-2020-e-beneficiar-4-milhoes-diz-governo.ghtml\">LEIA MAIS&#8230;&nbsp;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: G1&nbsp;&nbsp; O programa de prote\u00e7\u00e3o ao emprego ser\u00e1 renovado neste ano com o mesmo modelo adotado em 2020, e custar\u00e1 cerca de R$ 10 bilh\u00f5es, informou nesta ter\u00e7a-feira (30) o secret\u00e1rio especial de Previd\u00eancia e Trabalho do Minist\u00e9rio da Economia, Bruno Bianco.&nbsp; LEIA MAIS&#8230;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105],"tags":[],"_links":{"self":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts\/96565"}],"collection":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/comments?post=96565"}],"version-history":[{"count":0,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts\/96565\/revisions"}],"wp:attachment":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/media?parent=96565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/categories?post=96565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/tags?post=96565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}