{"id":101386,"date":"2021-10-28T17:47:25","date_gmt":"2021-10-28T20:47:25","guid":{"rendered":"https:\/\/acs.org.br\/antigo\/?p=101386"},"modified":"2021-10-29T09:00:28","modified_gmt":"2021-10-29T12:00:28","slug":"associacao-comercial-de-santos-entrega-proposta-de-iptu-verde-ao-prefeito-de-santos","status":"publish","type":"post","link":"https:\/\/acs.org.br\/academy\/associacao-comercial-de-santos-entrega-proposta-de-iptu-verde-ao-prefeito-de-santos\/","title":{"rendered":"Associa\u00e7\u00e3o Comercial de Santos entrega proposta de IPTU Verde ao prefeito de Santos"},"content":{"rendered":"<p>Fonte: Departamento de Comunica\u00e7\u00e3o\u00a0<\/p>\n<p>Com o objetivo de deixar um &#8216;presente&#8217; para o futuro, a Associa\u00e7\u00e3o Comercial de Santos (ACS) apresentou a seus associados e convidados, a agenda de sustentabilidade denominada ACS ESG, na manh\u00e3 desta quinta-feira, em seu audit\u00f3rio.\u00a0 Na ocasi\u00e3o,\u00a0 a entidade entregou uma propositura ao prefeito de Santos, Rog\u00e9rio Santos, para que o Munic\u00edpio crie o &#8216;IPTU Verde&#8217; e conceda descontos a propriet\u00e1rios de im\u00f3veis que implantem medidas sustent\u00e1veis.<\/p>\n<p>Em\u00a0 seu discurso de abertura, o presidente da ACS, Mauro Sammarco, falou sobre movimentos que existiram no passado e que deixaram legados.\u00a0 &#8220;Hoje, temos a sigla ESG &#8211; \u201cEnvironmental, Social and Governance\u201d (ambiental, social e governan\u00e7a, em portugu\u00eas). A \u00a0ESG, geralmente, \u00e9 usada para medir as pr\u00e1ticas ambientais, sociais e de governan\u00e7a de uma empresa e pode apontar o quanto um neg\u00f3cio busca formas de minimizar seus impactos no meio ambiente, construir um mundo mais justo e respons\u00e1vel para as pessoas em seu entorno e manter os melhores processos de administra\u00e7\u00e3o\u201d.<\/p>\n<p>O presidente ainda ressaltou que a\u00a0 ACS se compromete com o lan\u00e7amento de uma agenda ESG que trar\u00e1 inicialmente as \u00a0a\u00e7\u00f5es voltadas para o ambiente, social e Governan\u00e7a. \u201cAmbiental, com a gest\u00e3o dos impactos ambientais pela gera\u00e7\u00e3o de res\u00edduos e consumo de energia el\u00e9trica das nossas instala\u00e7\u00f5es (instalando sistema de energia solar);\u00a0 Social , com a educa\u00e7\u00e3o, forma\u00e7\u00e3o de talentos e empreendedorismo atrav\u00e9s da ACS Academy, em conex\u00e3o com a ACS Jovem (cursos, parcerias e programa de jovens empreendedores) e Governan\u00e7a, com a\u00a0 estrutura\u00e7\u00e3o e implementa\u00e7\u00e3o de Plano Estrat\u00e9gico para a gest\u00e3o da ACS\u201d.<\/p>\n<p>A ACS tamb\u00e9m desenvolver\u00e1 um calend\u00e1rio de eventos. No pr\u00f3ximo dia 04, haver\u00e1 a qualifica\u00e7\u00e3o de colaboradores e membros da ACS Jovem em pr\u00e1ticas de ESG. \u201cUm novo evento, voltado \u00e0 gera\u00e7\u00e3o de oportunidades para mulheres v\u00edtimas de viol\u00eancia dom\u00e9stica, ir\u00e1 ocorrer no final de novembro.\u00a0 A programa\u00e7\u00e3o continuar\u00e1 em 2022 e nos pr\u00f3ximos anos, com diversos eventos e iniciativas, incluindo o F\u00f3rum ESG, que ser\u00e1 realizado em meados de setembro e que premiar\u00e1 associadas que se destacarem pelas pr\u00e1ticas que envolvem o ESG&#8221;, explicou .<\/p>\n<p><strong>IPTU verde<\/strong><\/p>\n<p>A Associa\u00e7\u00e3o Comercial de Santos (ACS) prop\u00f4s \u00e0 Prefeitura de Santos, \u00e0 semelhan\u00e7a do que j\u00e1 existe em outras cidades brasileiras, \u00a0que estabele\u00e7a, atrav\u00e9s de Lei Complementar pr\u00f3pria, uma legisla\u00e7\u00e3o criando o \u201cIPTU Verde\u201d. \u00a0\u00a0\u201cO imposto consiste na institui\u00e7\u00e3o de descontos no valor do IPTU cobrado dos contribuintes que implementem em seus im\u00f3veis benfeitorias focadas na utiliza\u00e7\u00e3o sustent\u00e1vel dos recursos naturais&#8221;, explicou Sammarco.<\/p>\n<p>A proposta foi bem recebida pelo prefeito de Santos, Rog\u00e9rio Santos, que\u00a0 ir\u00e1 levar a quest\u00e3o para a C\u00e2mara de Vereadores para que a lei seja analisada e votada. <br \/>\n&#8220;A pauta da sustentabilidade e ambiental \u00e9 importante. Santos tem um papel importante. N\u00f3s fazemos parte, de um grupo de estudo internacional, e Santos \u00e9 a \u00fanica cidade brasileira, em parceria com universidade da Fl\u00f3rida e universidades europeias, que faz um trabalho cient\u00edfico e tecnol\u00f3gico para o monitoramento das mudan\u00e7as clim\u00e1ticas\u201d. <\/p>\n<p>O prefeito tamb\u00e9m falou que o Conselho de Desenvolvimento Urbano (Condesb) pretende impulsionar a\u00e7\u00f5es de mobilidade urbana sustent\u00e1vel e de baixo impacto poluente nos nove munic\u00edpios, com recursos do Programa Euroclima+, da Uni\u00e3o Europeia, que financia a\u00e7\u00f5es de mitiga\u00e7\u00e3o e adapta\u00e7\u00f5es aos efeitos das mudan\u00e7as clim\u00e1ticas. \u00a0<\/p>\n<p><strong>Programa #Voudebike<\/strong><\/p>\n<p>Antes do presidente da ACS, Mauro Sammarco, falar sobre a agenda de sustentabilidade, a associada da ACS,\u00a0 ModalGR,\u00a0 e a empresa, E-moving, lan\u00e7aram o projeto #voudebike. <\/p>\n<p>O programa disponibilizou 200 bicicletas el\u00e9tricas (e-bikes) para os que os colaboradores da ModalGR usem \u00e0 vontade, inclusive para fazer o trajeto at\u00e9 o escrit\u00f3rio. A ideia \u00e9 incentivar, cada vez mais,\u00a0 o uso deste meio de transporte sustent\u00e1vel.<\/p>\n<p>As e-bikes oferecidas\u00a0 t\u00eam uma bateria que carrega em tr\u00eas horas e uma autonomia de 25 km. De acordo com o diretor da ModalGR, \u00a0Luiz Sim\u00f5es,\u00a0 cada bicicleta ter\u00e1 um GPS para analisar quantos quil\u00f4metros\u00a0 os colaboradores andam por dia e, com essa medida, calcular o quanto de CO2 (polui\u00e7\u00e3o causada por ve\u00edculos automotores) deixou de ser emitido no meio ambiente.<\/p>\n<p>O outro diretor da ModalGR, Danilo Abbondanza, explicou que a empresa foi criada em 2015 e \u00e9 uma consultoria de tecnologia e inova\u00e7\u00e3o. \u201cA empresa \u00e9 nova e \u00a0tem como principal DNA a inova\u00e7\u00e3o. Hoje, atendemos os principais mercados, com foco log\u00edstico e portu\u00e1rio. Estamos expandido muito e vamos abrir um filial em Portugal neste final de semana, \u00a0e, ano que vem abriremos uma filial nos Estados Unidos. <\/p>\n<p>J\u00e1 o CEO da E-moving, Gabriel Arcon, explicou que a empresa nasceu h\u00e1 seis anos com o objetivo de ser a melhor op\u00e7\u00e3o de mobilidade urbana, de curta a m\u00e9dia dist\u00e2ncia. &#8220;Em S\u00e3o Paulo, onde ficamos, calculamos que a dist\u00e2ncia para o trabalho era de 7,8 quil\u00f4metros. Algo que d\u00e1 para percorrer de bicicleta. Acredito, que aqui em Santos, essa dist\u00e2ncia seja ainda menor. Nada mais justo que as empresa ofere\u00e7am essa facilidade ao colaborador\u201d. \u00a0<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-101396\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0304-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0304-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0304-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0304-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0304-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0304-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0304-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-101397\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0317-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0317-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0317-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0317-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0317-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0317-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0317-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-101399\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0332-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0332-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0332-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0332-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0332-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0332-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0332-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-101392\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0287-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0287-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0287-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0287-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0287-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0287-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0287-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-101393\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0291-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0291-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0291-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0291-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0291-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0291-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0291-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-101394\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0293-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0293-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0293-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0293-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0293-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0293-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0293-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-101395\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0295-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0295-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0295-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0295-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0295-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0295-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0295-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-101400\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0368-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0368-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0368-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0368-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0368-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0368-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0368-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-101402\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0375-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0375-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0375-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0375-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0375-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0375-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0375-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-101403\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0392-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0392-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0392-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0392-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0392-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0392-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0392-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-101388\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0249-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0249-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0249-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0249-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0249-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0249-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0249-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-101404\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0400-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0400-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0400-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0400-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0400-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0400-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0400-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-101390\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0273-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0273-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0273-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0273-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0273-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0273-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0273-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-101391\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0283-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0283-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0283-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0283-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0283-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0283-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/SUSTENTABILIDADE_0283-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Departamento de Comunica\u00e7\u00e3o\u00a0 Com o objetivo de deixar um &#8216;presente&#8217; para o futuro, a Associa\u00e7\u00e3o Comercial de Santos (ACS) apresentou a seus associados e convidados, a agenda de sustentabilidade denominada ACS ESG, na manh\u00e3 desta quinta-feira, em seu audit\u00f3rio.\u00a0 Na ocasi\u00e3o,\u00a0 a entidade entregou uma propositura ao prefeito de Santos, Rog\u00e9rio Santos, para que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":101401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114,84],"tags":[],"_links":{"self":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts\/101386"}],"collection":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/comments?post=101386"}],"version-history":[{"count":5,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts\/101386\/revisions"}],"predecessor-version":[{"id":101410,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts\/101386\/revisions\/101410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/media\/101401"}],"wp:attachment":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/media?parent=101386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/categories?post=101386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/tags?post=101386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}