{"id":101062,"date":"2021-10-19T16:38:27","date_gmt":"2021-10-19T19:38:27","guid":{"rendered":"https:\/\/acs.org.br\/antigo\/?p=101062"},"modified":"2021-10-19T16:59:32","modified_gmt":"2021-10-19T19:59:32","slug":"diretoria-da-acs-apresenta-pilares-estrategicos-as-camaras-setoriais","status":"publish","type":"post","link":"https:\/\/acs.org.br\/academy\/diretoria-da-acs-apresenta-pilares-estrategicos-as-camaras-setoriais\/","title":{"rendered":"Diretoria da ACS apresenta pilares estrat\u00e9gicos \u00e0s C\u00e2maras Setoriais"},"content":{"rendered":"<p>Fonte: Departamento de Comunica\u00e7\u00e3o da ACS<\/p>\n<p>Integrantes das C\u00e2maras Setoriais de Complexo de Soja, Navega\u00e7\u00e3o e Operadores Portu\u00e1rios participaram de uma reuni\u00e3o conjunta na tarde desta ter\u00e7a-feira (19) para conhecer os trabalhos que est\u00e3o sendo desenvolvidos pela diretoria da Associa\u00e7\u00e3o Comercial de Santos (ACS).<\/p>\n<p>Em pouco mais de uma hora, o presidente da ACS, Mauro Sammarco, junto ao diretor-executivo, Adalto Corr\u00eaa Jr e o gestor de neg\u00f3cios, Eduardo Lopes, apresentaram os pilares estrat\u00e9gicos desenvolvidos pela diretoria.<\/p>\n<p>Os cinco pilares (posicionamento, crescimento de receita, efici\u00eancia operacional, moderniza\u00e7\u00e3o e clima organizacional) para a reestrutura\u00e7\u00e3o da Institui\u00e7\u00e3o foram detalhados a todos associados.<\/p>\n<p>Cada pilar foi dividido nos setores que ACS representa como: Associados; Regional; Servi\u00e7os; Educa\u00e7\u00e3o; ACS Jovem e ACS Comunica\u00e7\u00e3o.<\/p>\n<p>Entre alguns destaques est\u00e3o a publica\u00e7\u00e3o do livro dos 150 anos, a prepara\u00e7\u00e3o para o Semin\u00e1rio Internacional do Caf\u00e9, as parcerias com o Sebrae, a Facesp e a Fapesp e a parceria com a Prefeitura de Santos nos eventos para a revitaliza\u00e7\u00e3o do Centro Hist\u00f3rico.<\/p>\n<p>At\u00e9 a pr\u00f3xima semana, a\u00a0diretoria ir\u00e1 se reunir com todas as c\u00e2maras setoriais para apresentar os projetos e programas implementados nos \u00faltimos 90 dias.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Departamento de Comunica\u00e7\u00e3o da ACS Integrantes das C\u00e2maras Setoriais de Complexo de Soja, Navega\u00e7\u00e3o e Operadores Portu\u00e1rios participaram de uma reuni\u00e3o conjunta na tarde desta ter\u00e7a-feira (19) para conhecer os trabalhos que est\u00e3o sendo desenvolvidos pela diretoria da Associa\u00e7\u00e3o Comercial de Santos (ACS). Em pouco mais de uma hora, o presidente da ACS, Mauro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":101065,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114,84],"tags":[],"_links":{"self":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts\/101062"}],"collection":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/comments?post=101062"}],"version-history":[{"count":7,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts\/101062\/revisions"}],"predecessor-version":[{"id":101071,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts\/101062\/revisions\/101071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/media\/101065"}],"wp:attachment":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/media?parent=101062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/categories?post=101062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/tags?post=101062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}