{"id":100715,"date":"2021-10-07T14:51:38","date_gmt":"2021-10-07T17:51:38","guid":{"rendered":"https:\/\/acs.org.br\/antigo\/?p=100715"},"modified":"2021-10-13T11:45:21","modified_gmt":"2021-10-13T14:45:21","slug":"camara-de-tecnologia-e-inovacao-da-acs-tracara-planejamento-para-o-setor","status":"publish","type":"post","link":"https:\/\/acs.org.br\/academy\/camara-de-tecnologia-e-inovacao-da-acs-tracara-planejamento-para-o-setor\/","title":{"rendered":"C\u00e2mara de Tecnologia da Informa\u00e7\u00e3o e Comunica\u00e7\u00e3o da ACS tra\u00e7ar\u00e1 planejamento para o setor"},"content":{"rendered":"<p>Fonte: Departamento de Comunica\u00e7\u00e3o da ACS<\/p>\n<p>Mostrar o potencial das empresas de tecnologia da regi\u00e3o e ser mais atuante nas outras C\u00e2maras da Associa\u00e7\u00e3o Comercial de Santos (ACS). Essas foram algumas das diretrizes discutidas pelos integrantes da C\u00e2mara de Tecnologia da Informa\u00e7\u00e3o e Comunica\u00e7\u00e3o da ACS na manh\u00e3 desta quinta-feira (07).<\/p>\n<p>De acordo com o coordenador da C\u00e2mara, Pedro Veras, os representantes das empresas devem se reunir mais vezes para tra\u00e7arem um plano de como podem contribuir com as outras C\u00e2maras da entidade. &#8220;O setor de tecnologia \u00e9 transversal e sempre traz novidades e facilidades a outros segmentos. Certamente encontraremos formas de sermos mais atuantes nos demais setores da ACS&#8221;.\u00a0\u00a0 \u00a0\u00a0<\/p>\n<p>Um outro ponto retratado pelos integrantes \u00e9 a falta de m\u00e3o de obra especializada. &#8220;A maioria das empresas tem vaga sobrando, mas n\u00e3o encontra profissional especializado para a \u00e1rea. Precisamos encontrar alguma forma de mudar essa realidade. Toda c\u00e2mara da ACS tem uma fun\u00e7\u00e3o de ser um cluster social. Aqui conseguimos reunir concorrentes e chegar a um consenso para trazer melhorias para o setor&#8221;, explicou Veras.<\/p>\n<p>No final da reuni\u00e3o, o diretor-executivo da ACS, Adalto Corr\u00eaa Jr, apresentou o planejamento estrat\u00e9gico da diretoria a curto, m\u00e9dio e a longo prazo. &#8220;J\u00e1 estamos desenvolvendo v\u00e1rias a\u00e7\u00f5es e parcerias para fortalecer ainda mais os servi\u00e7os e eventos oferecidos pela ACS&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-100725\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/IMG_4478-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4478-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4478-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4478-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4478-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4478-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4478-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-100724\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/IMG_4477-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4477-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4477-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4477-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4477-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4477-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4477-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> \u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-100721\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/IMG_4469-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4469-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4469-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4469-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4469-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4469-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4469-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-100720\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/IMG_4467-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4467-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4467-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4467-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4467-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4467-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4467-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-100719\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/IMG_4465-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4465-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4465-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4465-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4465-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4465-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4465-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-100722\" src=\"https:\/\/acs.org.br\/antigo\/wp-content\/uploads\/2021\/10\/IMG_4471-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4471-300x200.jpg 300w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4471-scaled-600x400.jpg 600w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4471-1024x683.jpg 1024w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4471-768x512.jpg 768w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4471-1536x1024.jpg 1536w, https:\/\/acs.org.br\/academy\/wp-content\/uploads\/2021\/10\/IMG_4471-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fonte: Departamento de Comunica\u00e7\u00e3o da ACS Mostrar o potencial das empresas de tecnologia da regi\u00e3o e ser mais atuante nas outras C\u00e2maras da Associa\u00e7\u00e3o Comercial de Santos (ACS). Essas foram algumas das diretrizes discutidas pelos integrantes da C\u00e2mara de Tecnologia da Informa\u00e7\u00e3o e Comunica\u00e7\u00e3o da ACS na manh\u00e3 desta quinta-feira (07). De acordo com o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114,84],"tags":[],"_links":{"self":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts\/100715"}],"collection":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/comments?post=100715"}],"version-history":[{"count":5,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts\/100715\/revisions"}],"predecessor-version":[{"id":100733,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/posts\/100715\/revisions\/100733"}],"wp:attachment":[{"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/media?parent=100715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/categories?post=100715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acs.org.br\/academy\/wp-json\/wp\/v2\/tags?post=100715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}